{"id":4165,"count":1,"description":"","link":"https:\/\/munichka.eu\/de\/t\/second-hand-laeden-in-muenchen","name":"Second-Hand-L\u00e4den in M\u00fcnchen","slug":"second-hand-laeden-in-muenchen","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/munichka.eu\/de\/wp-json\/wp\/v2\/tags\/4165","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/munichka.eu\/de\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/munichka.eu\/de\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/munichka.eu\/de\/wp-json\/wp\/v2\/posts?tags=4165"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}